{"id":594086,"date":"2022-06-21T19:06:12","date_gmt":"2022-06-21T17:06:12","guid":{"rendered":"http:\/\/biomes.world\/?p=594086"},"modified":"2024-02-14T08:58:22","modified_gmt":"2024-02-14T07:58:22","slug":"rezepte-und-anregungen","status":"publish","type":"post","link":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/","title":{"rendered":"Rezepte und Anregungen"},"content":{"rendered":"\n<p>Im Darm k\u00f6nnen sich sowohl gute, verdauungsf\u00f6rdernde Darmbakterien als auch schlechte Bakterien ansiedeln, die ein N\u00e4hrboden f\u00fcr Krankheiten sind. Erstgenannte gute Bakterien k\u00f6nnen durch Antibiotika, Radikaldi\u00e4ten und Erkrankungen angeschlagen sein: Oft ist dann eine geschw\u00e4chte Immunabwehr die Folge. <strong>Der Aufbau einer strapazierten Darmflora<\/strong> l\u00e4sst sich mit <strong>Rezepten f\u00fcr darmschonende Schonkost<\/strong> und leichte Vollkost aber unterst\u00fctzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-darmbakterien-und-gesundheit\">Darmbakterien und Gesundheit<\/h2>\n\n\n\n<p>Wir sind in unserem K\u00f6rper nicht allein. In und auf uns tummeln sich zehnmal so viele Kleinstlebewesen wie wir K\u00f6rperzellen haben. Zu unseren \u00fcberwiegend n\u00fctzlichen Mitbewohnern geh\u00f6ren unter anderem Am\u00f6ben, Milben, Pilze und Bakterien. Vor allem auf die Bakterien kommt es an. <strong>Die meisten n\u00fctzlichen Bakterien befinden sich im Verdauungstrakt<\/strong> \u2013 im D\u00fcnndarm und insbesondere im Dickdarm. Ihn besiedeln \u00fcber 1.400 Bakteriengattungen und insgesamt rund 100 Billionen einzelne Bakterien.<\/p>\n\n\n\n<p>Die Gesamtheit aller Darmbakterien macht unsere Darmflora aus. Die mikroskopisch kleinen Verdauungshelfer sitzen in der Darmschleimhaut. Dort spalten sie unverdauliche Nahrungsbestandteile auf, verwerten wichtige N\u00e4hrstoffe und trainieren das Immunsystem. <strong>Der allgemeine Gesundheitszustand h\u00e4ngt damit unmittelbar<\/strong> mit der Darmgesundheit zusammen. Rezepte f\u00fcr einen gesunden Darm sind dann gefragt, wenn die Darmflora geschw\u00e4cht ist und wieder aufgebaut werden muss.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-darmgesund-essen-schonkost-und-leichte-vollkost\">Darmgesund essen: Schonkost und leichte Vollkost<\/h2>\n\n\n\n<p><strong>Rezepte f\u00fcr darmschonende Kost<\/strong> beziehen sich auf eine Ern\u00e4hrung, die an bestimmte Krankheitsverl\u00e4ufe oder Verdauungsbeschwerden angepasst ist und somit die Genesung der Verdauungsorgane f\u00f6rdert. Liegt kein spezifisches Krankheitsbild vor, ist auch von leichter Vollkost oder allgemeiner Schonkost die Rede. Hierbei kommt es vor allem darauf an, sich <strong>vollwertig zu ern\u00e4hren<\/strong> und dem K\u00f6rper alle wichtigen N\u00e4hrstoffe in m\u00f6glichst leicht verdaulicher und vertr\u00e4glicher Form zuzuf\u00fchren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-neuester-beitrag\">Neuester Beitrag<\/h2>\n\n\n\n<div id=\"post-632905\" class=\"post__item--sticky post__item post-632905 post type-post status-publish format-standard has-post-thumbnail hentry category-ernaehrung category-rezepte-und-anregungen tag-darmflora tag-darmflora-aufbauen tag-darmgesundheit tag-ernaehrung\">\n    <div class=\"post__content\">\n\n        <div class=\"stage--sticky stage\">\n            <div class=\"stage__media--sticky stage__media\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"522\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-1314161102.jpg\" class=\"attachment-post-header size-post-header wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-1314161102.jpg 668w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-1314161102-300x234.jpg 300w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-1314161102-250x195.jpg 250w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><div class=\"post__thumbnail\"><\/div>            <\/div>\n            <div class=\"stage__header--sticky stage__header\">\n                <div class=\"stage__col column\">\n                    <div class=\"stage__title--sticky stage__title h1\">\n                        <span class=\"cat-links\"><a href=\"https:\/\/biomes.world\/de\/.\/wissenswertes\/ernaehrung\/\" rel=\"tag\">Ern\u00e4hrung<\/a>, <a href=\"https:\/\/biomes.world\/de\/.\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/\" rel=\"tag\">Rezepte &amp; Anregungen<\/a><\/span>                        <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/top-5-saisonalen-lebensmittel-fur-den-november-frische-power-fur-den-herbst\/\" aria-hidden=\"true\" tabindex=\"-1\">\n                            <strong>Top 5 saisonalen Lebensmittel f\u00fcr den November: Frische Power f\u00fcr den Sp\u00e4therbst<\/strong>                        <\/a>\n                    <\/div>\n                <\/div>\n                <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/top-5-saisonalen-lebensmittel-fur-den-november-frische-power-fur-den-herbst\/\" aria-hidden=\"true\" tabindex=\"-1\" class=\"stage__blocklink\">\n                    <span class=\"show-for-sr\"><strong>Top 5 saisonalen Lebensmittel f\u00fcr den November: Frische Power f\u00fcr den Sp\u00e4therbst<\/strong><\/span>\n                <\/a>\n            <\/div><!-- .stage__header -->\n        <\/div>\n\n    <\/div>\n<\/div><!-- #post-632905 -->\n\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-warum-rezepte-fur-die-darmgesundheit\">Warum Rezepte f\u00fcr die Darmgesundheit?<\/h2>\n\n\n\n<p>Sich mit Schonkost zu ern\u00e4hren, kann sinnvoll sein, wenn der Darm durch \u00e4u\u00dfere Einfl\u00fcsse oder Fremdk\u00f6rper gelitten hat. Dazu z\u00e4hlen unter anderem diese Erkrankungen und Syndrome:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmentzuendung\/\">Darmentz\u00fcndungen<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbeschwerden\/reizdarm-und-verdauung\/#\">Reizmagen<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbeschwerden\/reizdarm-und-verdauung\/reizdarm\/\">Reizdarm<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmflora\/darmprobleme-nach-antibiotika\/\">Durch Antibiotika geschw\u00e4chte Darmflora<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Auch psychische Faktoren und Erkrankungen k\u00f6nnen das Gleichgewicht im Darm durcheinanderbringen. <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darm-und-psyche\/\">Verantwortlich daf\u00fcr ist die Darm-Hirn-Achse<\/a>, die bislang noch nicht vollst\u00e4ndig erforscht ist. Sie bezeichnet die Wechselbeziehung zwischen seelischer Verfassung und Darmgesundheit.<\/p>\n\n\n\n<p>Liegt keine symptomatische Erkrankung, sondern <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbeschwerden\/unvertraeglichkeiten\/\">eine Lebensmittelunvertr\u00e4glichkeit<\/a> gegen bestimmte N\u00e4hrstoffe oder ein allgemein <strong>empfindlicher Magen<\/strong> vor, ist die sogenannte <strong>leichte Vollkost<\/strong> zu empfehlen. Eine leichte Vollkost versorgt den K\u00f6rper mit wichtigen N\u00e4hrstoffen in m\u00f6glichst leicht verdaulicher Form. Es fehlen alle Lebensmittel, die zu folgenden Verdauungsbeschwerden f\u00fchren k\u00f6nnen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbeschwerden\/reizdarm-und-verdauung\/blaehbauch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bl\u00e4hbauch<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbeschwerden\/reizdarm-und-verdauung\/blaehungen-ursachen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bl\u00e4hungen<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmbakterien\/darmbakterien-bei-verstopfung\/\">Verstopfung<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmgeraeusche\/\">Darmger\u00e4usche<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-weitere-beitrage\">Weitere Beitr\u00e4ge<\/h2>\n\n\n<div class=\"post__entries site-blockspace--both\"><div class=\"post__slide lg-up-3 md-up-2 xs-up-1 row\"><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/top-5-saisonalen-lebensmittel-fur-den-november-frische-power-fur-den-herbst\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-1314161102-668x470.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-09-11T12:43:30+02:00\" itemprop=\"datePublished\">11. September 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-09-17T16:25:31+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/top-5-saisonalen-lebensmittel-fur-den-november-frische-power-fur-den-herbst\/\">Top 5 saisonalen Lebensmittel f\u00fcr den November: Frische Power f\u00fcr den Sp\u00e4therbst<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Der November bietet eine F\u00fclle an frischen, n\u00e4hrstoffreichen Lebensmitteln, die ideal f\u00fcr die k\u00e4lteren Tage sind. Mit diesen saisonalen Sch\u00e4tzen [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/saisonale-lebensmittel-fur-den-oktober-und-herbst\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/09\/iStock-861445168-724x470.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Zutaten saisonale Rezepte Oktober\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-09-11T11:26:44+02:00\" itemprop=\"datePublished\">11. September 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-09-11T11:33:40+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/saisonale-lebensmittel-fur-den-oktober-und-herbst\/\">Top 5 saisonalen Lebensmittel f\u00fcr den Oktober: N\u00e4hrstoffreiche Vielfalt im Herbst<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Der Oktober bringt eine F\u00fclle an frischen, n\u00e4hrstoffreichen Lebensmitteln mit sich, die nicht nur k\u00f6stlich sind, sondern auch deine Gesundheit [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/5-saisonale-lebensmittel-im-september-leckere-und-gesunde-rezeptideen\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/08\/jan-canty-XaLE4wF6s-unsplash-800x470.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/08\/jan-canty-XaLE4wF6s-unsplash-800x470.jpg 800w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/08\/jan-canty-XaLE4wF6s-unsplash-400x235.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-08-09T15:02:10+02:00\" itemprop=\"datePublished\">9. August 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-08-09T15:02:16+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/5-saisonale-lebensmittel-im-september-leckere-und-gesunde-rezeptideen\/\">5 Saisonale Lebensmittel im September: Leckere und gesunde Rezeptideen<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Der September markiert den \u00dcbergang vom Sommer zum Herbst und bringt eine besondere Atmosph\u00e4re mit sich. Die Tage werden k\u00fcrzer, [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/darmfreundliche-rezepte-mit-saisonalen-zutaten-fuer-den-august\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/DALL\u00b7E-2024-07-24-09.20.43-A-wide-aspect-ratio-image-showcasing-seasonal-fruits-and-vegetables-available-in-August.-The-image-includes-fresh-green-beans-cucumbers-zucchini-va-800x470.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/DALL\u00b7E-2024-07-24-09.20.43-A-wide-aspect-ratio-image-showcasing-seasonal-fruits-and-vegetables-available-in-August.-The-image-includes-fresh-green-beans-cucumbers-zucchini-va-800x470.webp 800w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/DALL\u00b7E-2024-07-24-09.20.43-A-wide-aspect-ratio-image-showcasing-seasonal-fruits-and-vegetables-available-in-August.-The-image-includes-fresh-green-beans-cucumbers-zucchini-va-400x235.webp 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-07-24T14:42:35+02:00\" itemprop=\"datePublished\">24. Juli 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-07-24T14:42:41+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/darmfreundliche-rezepte-mit-saisonalen-zutaten-fuer-den-august\/\">Darmfreundliche Rezepte mit saisonalen Zutaten f\u00fcr den August<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Der August bringt eine F\u00fclle an frischen, saisonalen Lebensmitteln, die deine Darmflora st\u00e4rken k\u00f6nnen. Diese leckeren Zutaten helfen dir, gesund [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/grillen-und-darmgesundheit-gesunde-grillalternative-fuer-deine-darmflora\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/daniel-hooper-ovzXxr6webc-unsplash-800x470.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/daniel-hooper-ovzXxr6webc-unsplash-800x470.jpg 800w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/daniel-hooper-ovzXxr6webc-unsplash-400x235.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-07-15T12:28:48+02:00\" itemprop=\"datePublished\">15. Juli 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-07-15T12:28:51+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/grillen-und-darmgesundheit-gesunde-grillalternative-fuer-deine-darmflora\/\">Grillen und Darmgesundheit: Gesunde Grillalternative f\u00fcr deine Darmflora<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Das Grillen im Sommer geh\u00f6rt f\u00fcr viele einfach dazu, aber traditionelle Grillgerichte sind nicht immer gut f\u00fcr unsere Darmgesundheit. Gl\u00fccklicherweise [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/urlaub-und-mediterrane-ernaehrung-eine-darmfreundliche-kombination\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/jez-timms-BHD2OxkYGSk-unsplash-800x470.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/jez-timms-BHD2OxkYGSk-unsplash-800x470.jpg 800w, https:\/\/biomes.world\/wp-content\/uploads\/2024\/07\/jez-timms-BHD2OxkYGSk-unsplash-400x235.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2024-07-10T16:14:27+02:00\" itemprop=\"datePublished\">10. Juli 2024<\/time><time class=\"meta__date--updated\" datetime=\"2024-07-10T16:14:31+02:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/urlaub-und-mediterrane-ernaehrung-eine-darmfreundliche-kombination\/\">Urlaub und mediterrane Ern\u00e4hrung: Eine darmfreundliche Kombination<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Ein Urlaub ist nicht nur eine Zeit der Erholung und Entspannung, sondern auch eine Gelegenheit, neue Ern\u00e4hrungsgewohnheiten zu entdecken. Die [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><\/div><\/div>\n\n<div class=\"post__entries site-block site-blockspace--bottom\"><div class=\"lg-up-3 md-up-2 xs-up-1 row\"><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/test-lebensmittelunvertraeglichkeit-so-findest-du-heraus-was-dir-nicht-bekommt\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-37-800x470.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Test Lebensmittelunvertr\u00e4glichkeit \u2013 So findest du heraus, was dir nicht bekommt\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-37-800x470.png 800w, https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-37-400x235.png 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2025-11-26T04:26:21+01:00\" itemprop=\"datePublished\">26. November 2025<\/time><time class=\"meta__date--updated\" datetime=\"2026-01-22T14:16:18+01:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/test-lebensmittelunvertraeglichkeit-so-findest-du-heraus-was-dir-nicht-bekommt\/\">Test Lebensmittelunvertr\u00e4glichkeit \u2013 So findest du heraus, was dir nicht bekommt<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Lebensmittelunvertr\u00e4glichkeiten k\u00f6nnen den Alltag massiv beeintr\u00e4chtigen: Bl\u00e4hungen, Durchfall, Hautprobleme oder st\u00e4ndige M\u00fcdigkeit sind nur einige der Symptome, die nach dem [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/probiotika-scheidenflora-unterstuetzung-von-innen\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-35-800x470.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Probiotika Scheidenflora \u2013 Unterst\u00fctzung von innen\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-35-800x470.png 800w, https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-35-400x235.png 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2025-11-26T04:24:19+01:00\" itemprop=\"datePublished\">26. November 2025<\/time><time class=\"meta__date--updated\" datetime=\"2026-01-22T14:15:19+01:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/probiotika-scheidenflora-unterstuetzung-von-innen\/\">Probiotika Scheidenflora \u2013 Unterst\u00fctzung von innen<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Eine gesunde Scheidenflora ist der beste Schutz vor Infektionen, Reizungen und unangenehmen Beschwerden. Doch hormonelle Schwankungen, Stress, Antibiotika oder unausgewogene [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/ernaehrungsplan-darmsanierung-schritt-fuer-schritt-zu-einem-gesunden-mikrobiom\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-31-800x470.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Ern\u00e4hrungsplan Darmsanierung: Schritt f\u00fcr Schritt zu einem gesunden Mikrobiom\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-31-800x470.png 800w, https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-31-400x235.png 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2025-11-26T04:20:08+01:00\" itemprop=\"datePublished\">26. November 2025<\/time><time class=\"meta__date--updated\" datetime=\"2026-01-22T14:11:40+01:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/ernaehrungsplan-darmsanierung-schritt-fuer-schritt-zu-einem-gesunden-mikrobiom\/\">Ern\u00e4hrungsplan Darmsanierung: Schritt f\u00fcr Schritt zu einem gesunden Mikrobiom<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Eine Darmsanierung gilt als bew\u00e4hrte Methode, um die Darmflora zu st\u00e4rken, Beschwerden zu lindern und langfristig das Wohlbefinden zu steigern. [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><div class=\"post__item post column\">\n                <div class=\"post__content\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/fructoseintoleranz-probiotika-was-du-wissen-solltest\/\" class=\"post__thumbnail\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-29-1-800x470.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bildbeschreibung\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-29-1-800x470.png 800w, https:\/\/biomes.world\/wp-content\/uploads\/2025\/11\/Rectangle-29-1-400x235.png 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n                    <div class=\"entry\">\n                        <div class=\"entry__meta\"><span class=\"meta__posted-on\">Ver\u00f6ffentlicht am <time class=\"meta__date meta__date--published\" datetime=\"2025-11-26T04:16:45+01:00\" itemprop=\"datePublished\">26. November 2025<\/time><time class=\"meta__date--updated\" datetime=\"2026-01-22T14:09:52+01:00\" itemprop=\"dateModified\"><\/time><\/span><\/div>\n                        <div class=\"entry__header\">\n                            <div class=\"entry__title h2\"><a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/fructoseintoleranz-probiotika-was-du-wissen-solltest\/\">Fructoseintoleranz &amp; Probiotika: Was du wissen solltest<\/a><\/div>\n                        <\/div><div class=\"entry__excerpt\"><p>Fructoseintoleranz kann mehr als nur Verdauungsprobleme verursachen, sie beeintr\u00e4chtigt das t\u00e4gliche Wohlbefinden und bringt oft Unsicherheiten bei der Lebensmittelauswahl mit [&#8230;]<\/p><\/div><\/div>\n                <\/div>\n            <\/div><\/div><div class=\"site-blockspace--both text-center row\"><div class=\"column\"><button class=\"wp-block-button__link post__loadmore\" data-limit=\"4\" data-slug=\"ernaehrung\" data-hide-excerpt=\"0\">Mehr Artikel lesen<\/button><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-darmsanierung-durch-schonende-ernahrung\">Darmsanierung durch schonende Ern\u00e4hrung<\/h2>\n\n\n\n<p>Die <strong>Darmbakterien werden von der Ern\u00e4hrung beeinflusst.<\/strong> Je nachdem, wie gesund oder ungesund du dich ern\u00e4hrst, haben die kleinen Verdauungshelfer einen leichten oder harten Job. Die Lebensmittel, die du \u00fcberwiegend isst \u2013 also zum Beispiel vorrangig Gem\u00fcse oder Fleisch, frische Kost oder Fertigprodukte \u2013 ver\u00e4ndern auf Dauer die Zusammensetzung der Darmflora und st\u00e4rken oder reduzieren n\u00fctzliche Bakterienst\u00e4mme. So weisen <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/vegetarisch-pro-und-contra\/\">Vegetarier<\/a> im Darm mehr Kohlenhydrate verarbeitende Bakterien auf, wohingegen bei Fleischessern Bakterien dominieren, die Enzyme zur Eiwei\u00dfspaltung produzieren.<\/p>\n\n\n\n<p>Rezepte f\u00fcr Darmgesundheit und Darmsanierung enthalten oft <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/darmflora\/hausmittel-fuer-deine-darmflora\/\">Haus- bzw. Lebensmittel<\/a>, die sich bei einem geschw\u00e4chten Darm bew\u00e4hrt haben. Mit einem <strong>speziell auf deine Darmflora <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/ernaehrungsplan\/personalisierte-ernaehrung\/\">abgestimmten Ern\u00e4hrungsplan<\/a><\/strong>, den Wissenschaftler*innen von <strong>BIOMES<\/strong> f\u00fcr dich zusammenstellen, kannst du gezielt Rezepte und Lebensmittel ausw\u00e4hlen, die deinem Darm guttun.<\/p>\n\n\n\n<p>Wenn du unter Verdauungsbeschwerden leidest und bereits \u00fcber eine Darmsanierung nachdenkst, erm\u00f6glicht es dir der <a href=\"https:\/\/biomes.world\/de\/feel-better\/intest-pro\/\">Darmtest <strong>INTEST<\/strong>.pro<\/a> von <strong>BIOMES<\/strong>, die <strong>Zusammensetzung deiner Darmflora mittels eines Testverfahrens<\/strong> nach h\u00f6chstem biotechnischem Standard zu ermitteln. Darauf basierend kannst du gegebenenfalls deine Ern\u00e4hrung mit <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/probiotika\/\">probiotischen Nahrungs&shy;erg\u00e4nzungs&shy;mitteln<\/a> unterst\u00fctzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-eine-ausgeglichene-darmflora-lindert-darmbeschwerden\">Eine ausgeglichene Darmflora lindert Darmbeschwerden<\/h2>\n\n\n\n<p>Um die Darmflora wiederherzustellen, ist eine genaue Analyse der Ursachen des Ungleichgewichts notwendig. Mit <strong>INTEST.<\/strong>pro bringt die <strong>BIOMES<\/strong> die erste vollst\u00e4ndige Darmflora-Analyse auf den Markt, die individuelle Empfehlungen zur Steigerung der Gesundheit, des Wohlbefindens und der Lebensqualit\u00e4t enth\u00e4lt.<\/p>\n\n\n\n<p><strong>INTEST.<\/strong>pro ist ein Selbsttest zur Entnahme einer Stuhlprobe in vertrauter Umgebung, der die mikrobielle Beschaffenheit, d.h. die Anzahl und Verteilung der Darmbakterien, ermittelt.<\/p>\n\n\n\n<p>Das Gleichgeweicht der Darmflora kann durch die Einnahme von Probiotika oder probiotischen Lebensmitteln unterst\u00fctzt werden. Mehr Informationen dazu findest du auf unserer Info-Seite zu <a href=\"https:\/\/biomes.world\/de\/wissenswertes\/darm\/probiotika\/\">Probiotika<\/a>.<\/p>\n\n\n    <section class=\"cta horizontal_split\">\n        <div class=\"image_container light_purple-background\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-800x800.webp\" class=\"product__img\" alt=\"darmflora-test-erwachsene\" srcset=\"https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-300x300.webp 300w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-1024x1024.webp 1024w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-150x150.webp 150w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-768x769.webp 768w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-800x800.webp 800w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-250x250.webp 250w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-100x100.webp 100w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene-400x400.webp 400w, https:\/\/biomes.world\/wp-content\/uploads\/2023\/06\/darmflora-test-erwachsene.webp 1206w\" sizes=\"auto, (max-width: 30em) 100vw, (max-width: 48em) 100vw, (max-width: 62em) 1000vw, (max-width: 75em) 800px, 800px\" \/><div class=\"figure_tag\">159 EUR<\/div>        <\/div>\n        <div class=\"vertical_center_child white-background\">\n            <div>\n                <h2>Finde heraus, was deinem Darm gut tut<\/h2>                <p>Bestelle jetzt die Darmfloraanalyse <b>INTEST<\/b>.pro und starte ein gl\u00fcckliches Leben.<\/p>                <button class=\"yellow_theme--button yellow\"><a href=\"https:\/\/shop.biomes.world\/products\/intest-pro\">Jetzt bestellen<\/a><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"<p>Der November bietet eine F\u00fclle an frischen, n\u00e4hrstoffreichen Lebensmitteln, die ideal f\u00fcr die k\u00e4lteren Tage sind. Mit diesen saisonalen Sch\u00e4tzen [&#8230;]<\/p>\n","protected":false},"author":3168,"featured_media":505769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[342],"tags":[],"class_list":["post-594086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rezepte und Anregungen - BIOMES - Feel better<\/title>\n<meta name=\"description\" content=\"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rezepte und Anregungen - BIOMES - Feel better\" \/>\n<meta property=\"og:description\" content=\"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOMES - Feel better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/BIOMES.world\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-21T17:06:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T07:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Paul Hammer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Paul Hammer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/\"},\"author\":{\"name\":\"Dr. Paul Hammer\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#\\\/schema\\\/person\\\/6ca9c5d1dd4da421e107092bf1235957\"},\"headline\":\"Rezepte und Anregungen\",\"datePublished\":\"2022-06-21T17:06:12+00:00\",\"dateModified\":\"2024-02-14T07:58:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/\"},\"wordCount\":722,\"publisher\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Rezepte.jpg\",\"articleSection\":[\"Ern\u00e4hrung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/\",\"url\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/\",\"name\":\"Rezepte und Anregungen - BIOMES - Feel better\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Rezepte.jpg\",\"datePublished\":\"2022-06-21T17:06:12+00:00\",\"dateModified\":\"2024-02-14T07:58:22+00:00\",\"description\":\"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Rezepte.jpg\",\"contentUrl\":\"https:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Rezepte.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Kategoriefoto Ern\u00e4hrung Nahaufnahme Topview Arbeitsplatte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/wissenswertes\\\/ernaehrung\\\/rezepte-und-anregungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/biomes.world\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rezepte und Anregungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/biomes.world\\\/de\\\/\",\"name\":\"BIOMES - Feel better\",\"description\":\"Cutting-edge biotechnology used to help people\",\"publisher\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biomes.world\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#organization\",\"name\":\"BIOMES 4.0 GmbH\",\"url\":\"https:\\\/\\\/biomes.world\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biomes.world\\\/http:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/biomes_logo_2021_RGB.png\",\"contentUrl\":\"https:\\\/\\\/biomes.world\\\/http:\\\/\\\/biomes.world\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/biomes_logo_2021_RGB.png\",\"width\":10040,\"height\":2599,\"caption\":\"BIOMES 4.0 GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/BIOMES.world\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@BIOMESworld\",\"https:\\\/\\\/www.instagram.com\\\/biomes_official\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biomes.world\\\/de\\\/#\\\/schema\\\/person\\\/6ca9c5d1dd4da421e107092bf1235957\",\"name\":\"Dr. Paul Hammer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g\",\"caption\":\"Dr. Paul Hammer\"},\"description\":\"Dr. Paul Hammer ist Gr\u00fcnder und CEO der BIOMES 4.0 GmbH. Paul promovierte 2012 in Systembiologie und Bioinformatik.\",\"url\":\"https:\\\/\\\/biomes.world\\\/de\\\/author\\\/paul_hammer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rezepte und Anregungen - BIOMES - Feel better","description":"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/","og_locale":"de_DE","og_type":"article","og_title":"Rezepte und Anregungen - BIOMES - Feel better","og_description":"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.","og_url":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/","og_site_name":"BIOMES - Feel better","article_publisher":"https:\/\/de-de.facebook.com\/BIOMES.world\/","article_published_time":"2022-06-21T17:06:12+00:00","article_modified_time":"2024-02-14T07:58:22+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg","type":"image\/jpeg"}],"author":"Dr. Paul Hammer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dr. Paul Hammer","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#article","isPartOf":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/"},"author":{"name":"Dr. Paul Hammer","@id":"https:\/\/biomes.world\/de\/#\/schema\/person\/6ca9c5d1dd4da421e107092bf1235957"},"headline":"Rezepte und Anregungen","datePublished":"2022-06-21T17:06:12+00:00","dateModified":"2024-02-14T07:58:22+00:00","mainEntityOfPage":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/"},"wordCount":722,"publisher":{"@id":"https:\/\/biomes.world\/de\/#organization"},"image":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#primaryimage"},"thumbnailUrl":"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg","articleSection":["Ern\u00e4hrung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/","url":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/","name":"Rezepte und Anregungen - BIOMES - Feel better","isPartOf":{"@id":"https:\/\/biomes.world\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#primaryimage"},"image":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#primaryimage"},"thumbnailUrl":"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg","datePublished":"2022-06-21T17:06:12+00:00","dateModified":"2024-02-14T07:58:22+00:00","description":"Entdecke neue Rezepte und Anregungen f\u00fcr eine darmgesunde Ern\u00e4hrung. Zusammengestellt f\u00fcr dich und deinen Darm von unseren Experten.","breadcrumb":{"@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#primaryimage","url":"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg","contentUrl":"https:\/\/biomes.world\/wp-content\/uploads\/2021\/05\/Rezepte.jpg","width":1000,"height":1000,"caption":"Kategoriefoto Ern\u00e4hrung Nahaufnahme Topview Arbeitsplatte"},{"@type":"BreadcrumbList","@id":"https:\/\/biomes.world\/de\/wissenswertes\/ernaehrung\/rezepte-und-anregungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biomes.world\/de\/"},{"@type":"ListItem","position":2,"name":"Rezepte und Anregungen"}]},{"@type":"WebSite","@id":"https:\/\/biomes.world\/de\/#website","url":"https:\/\/biomes.world\/de\/","name":"BIOMES - Feel better","description":"Cutting-edge biotechnology used to help people","publisher":{"@id":"https:\/\/biomes.world\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biomes.world\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/biomes.world\/de\/#organization","name":"BIOMES 4.0 GmbH","url":"https:\/\/biomes.world\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biomes.world\/de\/#\/schema\/logo\/image\/","url":"https:\/\/biomes.world\/http:\/\/biomes.world\/wp-content\/uploads\/2024\/04\/biomes_logo_2021_RGB.png","contentUrl":"https:\/\/biomes.world\/http:\/\/biomes.world\/wp-content\/uploads\/2024\/04\/biomes_logo_2021_RGB.png","width":10040,"height":2599,"caption":"BIOMES 4.0 GmbH"},"image":{"@id":"https:\/\/biomes.world\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/BIOMES.world\/","https:\/\/www.youtube.com\/@BIOMESworld","https:\/\/www.instagram.com\/biomes_official\/"]},{"@type":"Person","@id":"https:\/\/biomes.world\/de\/#\/schema\/person\/6ca9c5d1dd4da421e107092bf1235957","name":"Dr. Paul Hammer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b9ca6439b8f81c0c7fdfcce69b1ac9671bb451f6222e3fdad8a5d69827081a7?s=96&d=mm&r=g","caption":"Dr. Paul Hammer"},"description":"Dr. Paul Hammer ist Gr\u00fcnder und CEO der BIOMES 4.0 GmbH. Paul promovierte 2012 in Systembiologie und Bioinformatik.","url":"https:\/\/biomes.world\/de\/author\/paul_hammer\/"}]}},"_links":{"self":[{"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/posts\/594086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/users\/3168"}],"replies":[{"embeddable":true,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/comments?post=594086"}],"version-history":[{"count":6,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/posts\/594086\/revisions"}],"predecessor-version":[{"id":631211,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/posts\/594086\/revisions\/631211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/media\/505769"}],"wp:attachment":[{"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/media?parent=594086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/categories?post=594086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biomes.world\/de\/wp-json\/wp\/v2\/tags?post=594086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}